{"id":5358,"date":"2024-06-11T16:47:56","date_gmt":"2024-06-11T14:47:56","guid":{"rendered":"https:\/\/letolab.websols.nl\/diensten\/cad-digitaal-tekenwerk\/"},"modified":"2025-04-15T12:01:32","modified_gmt":"2025-04-15T10:01:32","slug":"cad-digital-engineering","status":"publish","type":"page","link":"https:\/\/www.letolab.nl\/en\/services\/cad-digital-engineering\/","title":{"rendered":"CAD &#8211; Digital Engineering"},"content":{"rendered":"<div id='full_slider_1'  class='avia-fullwidth-slider main_color avia-shadow   avia-builder-el-0  el_before_av_section  avia-builder-el-first   container_wrap fullsize'  ><div  class='avia-slideshow av-m49sovdj-0e3afc6ea9af6be804e7eabbb57ec524 avia-slideshow-featured av_slideshow_full avia-slide-slider av-slideshow-ui av-control-default av-slideshow-autoplay av-loop-endless av-loop-manual-endless av-default-height-applied   avia-slideshow-1' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:true,&quot;loop_autoplay&quot;:&quot;endless&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 28.666666666667%;'><li  class='avia-slideshow-slide av-m49sovdj-0e3afc6ea9af6be804e7eabbb57ec524__0  av-single-slide slide-1 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><div class='av-slideshow-caption av-m49sovdj-0e3afc6ea9af6be804e7eabbb57ec524__0 caption_fullwidth caption_center'><div class=\"container caption_container\"><div class=\"slideshow_caption\"><div class=\"slideshow_inner_caption\"><div class=\"slideshow_align_caption\"><h1 class='avia-caption-title '  itemprop=\"name\" >CAD - Digital Engineering<\/h1><br\/><a href='https:\/\/www.letolab.nl\/en\/projects\/'  class='avia-slideshow-button avia-button avia-color-theme-color-highlight avia-multi-slideshow-button' data-duration='800' data-easing='easeInOutQuad'>Projects<\/a><a href='https:\/\/www.letolab.nl\/en\/contact\/'  class='avia-slideshow-button avia-button avia-color-theme-color-subtle avia-multi-slideshow-button avia-slideshow-button-2' data-duration='800' data-easing='easeInOutQuad'>Contact<\/a><\/div><\/div><\/div><\/div><\/div><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-5129 avia-img-lazy-loading-not-5129\"  src=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241216_110958106_iOS-1500x430.jpg\" width=\"1500\" height=\"430\" title='3D CAD' alt=''  itemprop=\"thumbnailUrl\"  style='min-height:430px; min-width:1500px; ' \/><div class='av-section-color-overlay' style='opacity: 0.5; background-color: #141414; '><\/div><\/div><\/li><\/ul><\/div><\/div>\n<div id='av_section_1'  class='avia-section av-1yurwyg-2842980615e166c106ddf5462fd70e72 main_color avia-section-default avia-no-border-styling  avia-builder-el-1  el_after_av_slideshow_full  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-5358'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-1wt5gag-5a752223d19435efbb40685b5e2d26ee av_one_fifth  avia-builder-el-2  el_before_av_three_fifth  avia-builder-el-first  first av-break-at-tablet flex_column_div  '     ><\/div><div  class='flex_column av-6qsup4-13ced8530b041b16729dc3474916c007 av_three_fifth  avia-builder-el-3  el_after_av_one_fifth  el_before_av_one_fifth  av-break-at-tablet flex_column_div  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1t4fxjs-40e4afabd7916628af4a02f69de3e3c8\">\n#top .av_textblock_section.av-1t4fxjs-40e4afabd7916628af4a02f69de3e3c8 .avia_textblock{\ntext-align:center;\n}\n<\/style>\n<section  class='av_textblock_section av-1t4fxjs-40e4afabd7916628af4a02f69de3e3c8 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>From concept to visualization and production-ready design,<br \/>\nCAD transforms your ideas into a digital reality.<\/p>\n<\/div><\/section><\/div><div  class='flex_column av-1rxrkwo-4f7c1885c27dd69a0cbb382121a8321e av_one_fifth  avia-builder-el-5  el_after_av_three_fifth  avia-builder-el-last  av-break-at-tablet flex_column_div  '     ><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_2'  class='avia-section av-67b4co-7070ee4d416ed542205db5daacb1fef1 main_color avia-section-default avia-no-border-styling  avia-builder-el-6  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-5358'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-1orh7mg-3ff79e4a9c12f2f17fae12074d77dbaf av_one_half  avia-builder-el-7  el_before_av_one_half  avia-builder-el-first  first flex_column_div  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1mmp5g8-3358fc2a6d198eda977d1acacd08471c\">\n.avia-image-container.av-1mmp5g8-3358fc2a6d198eda977d1acacd08471c img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-1mmp5g8-3358fc2a6d198eda977d1acacd08471c .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-1mmp5g8-3358fc2a6d198eda977d1acacd08471c av-styling- avia-align-center  avia-builder-el-8  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-5122 avia-img-lazy-loading-not-5122 avia_image ' src=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/10\/Lasersnijden-1024x768.jpg\" alt='' title='Lasersnijden'  height=\"768\" width=\"1024\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/10\/Lasersnijden-1024x768.jpg 1024w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/10\/Lasersnijden-300x225.jpg 300w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/10\/Lasersnijden-768x576.jpg 768w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/10\/Lasersnijden-1536x1152.jpg 1536w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/10\/Lasersnijden-1500x1125.jpg 1500w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/10\/Lasersnijden-705x529.jpg 705w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/10\/Lasersnijden.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><div  class='flex_column av-1l1z6nc-c89d45e4442bf9488c113545f896e705 av_one_half  avia-builder-el-9  el_after_av_one_half  el_before_av_one_half  flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1j7vus8-f8da24404b225641f4dcf11b9a79a27f\">\n#top .av-special-heading.av-1j7vus8-f8da24404b225641f4dcf11b9a79a27f{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-1j7vus8-f8da24404b225641f4dcf11b9a79a27f .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-1j7vus8-f8da24404b225641f4dcf11b9a79a27f .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-1j7vus8-f8da24404b225641f4dcf11b9a79a27f av-special-heading-h2 blockquote modern-quote  avia-builder-el-10  el_before_av_textblock  avia-builder-el-first '><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >Your Design, Machine-Ready<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-1hv4gc8-fed42cb92d13503db27bfcddfe9977cc '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>I\u2019ll make sure your design is fully prepared for the <a href=\"https:\/\/www.letolab.nl\/en\/services\/laser-cutting-engraving\/\">laser cutter<\/a> or <a href=\"https:\/\/www.letolab.nl\/en\/services\/cam-cnc-routing\/\">CNC router<\/a>. Only have a rough sketch? No problem! I\u2019ll turn your plans into a manufacturable and successful product. Always with clear communication and full collaboration.<\/p>\n<\/div><\/section><br \/>\n<div  class='avia-buttonrow-wrap av-1guu30o-1384b90c8277d318c3d0ffeba8f9dd54 avia-buttonrow-left  avia-builder-el-12  el_after_av_textblock  avia-builder-el-last '>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1erego8-e3f3722c8597dd51bf70dea33cb692d8\">\n#top #wrap_all .avia-button.av-1erego8-e3f3722c8597dd51bf70dea33cb692d8{\nmargin-bottom:5px;\nmargin-right:5px;\n}\n<\/style>\n<a href='https:\/\/www.letolab.nl\/en\/faqs\/'  class='avia-button av-1erego8-e3f3722c8597dd51bf70dea33cb692d8 avia-icon_select-no avia-size-large avia-color-theme-color'   aria-label=\"Frequently Asked Questions\"><span class='avia_iconbox_title' >Frequently Asked Questions<\/span><\/a>\n<\/div><\/p><\/div><div  class='flex_column av-1da80x4-5091398b6ebfbe2287112d0fdcaa4886 av_one_half  avia-builder-el-13  el_after_av_one_half  el_before_av_one_half  first flex_column_div  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1akp0bc-584e6ceea7d3562306fe16f9da53b4d0\">\n#top .av-special-heading.av-1akp0bc-584e6ceea7d3562306fe16f9da53b4d0{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-1akp0bc-584e6ceea7d3562306fe16f9da53b4d0 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-1akp0bc-584e6ceea7d3562306fe16f9da53b4d0 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-1akp0bc-584e6ceea7d3562306fe16f9da53b4d0 av-special-heading-h2 blockquote modern-quote  avia-builder-el-14  el_before_av_textblock  avia-builder-el-first '><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >Experience That Makes a Difference<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-19xitg8-2dafc5fa3cb0683fb31ba228bc8cc1b8 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>With over 20 years of experience in CAD and digital manufacturing, I spot opportunities to improve your design and ensure a smooth production process. I move seamlessly between 2D and 3D, using visualizations to keep everybody on the same page. This way, we prepare your design for flawless manufacturing.<\/p>\n<\/div><\/section><br \/>\n<div  class='avia-buttonrow-wrap av-17ks6x4-2047d5e161e8c4a9feecf09ee1ecf63d avia-buttonrow-left  avia-builder-el-16  el_after_av_textblock  avia-builder-el-last '>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-15zv5hk-381315bc258688af76a361eb2150351c\">\n#top #wrap_all .avia-button.av-15zv5hk-381315bc258688af76a361eb2150351c{\nmargin-bottom:5px;\nmargin-right:5px;\n}\n<\/style>\n<a href='https:\/\/www.letolab.nl\/en\/contact\/'  class='avia-button av-15zv5hk-381315bc258688af76a361eb2150351c avia-icon_select-no avia-size-large avia-color-theme-color'   aria-label=\"Request Quote\"><span class='avia_iconbox_title' >Request Quote<\/span><\/a>\n<\/div><\/p><\/div><div  class='flex_column av-1456lqg-93ced523c4095618bcfdd4ccbb62907d av_one_half  avia-builder-el-17  el_after_av_one_half  el_before_av_one_half  flex_column_div  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-127r8vs-be18e87c65a7f2a4f840a58a9f7de54f\">\n.avia-image-container.av-127r8vs-be18e87c65a7f2a4f840a58a9f7de54f img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-127r8vs-be18e87c65a7f2a4f840a58a9f7de54f .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-127r8vs-be18e87c65a7f2a4f840a58a9f7de54f av-styling- avia-align-center  avia-builder-el-18  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-5132 avia-img-lazy-loading-not-5132 avia_image ' src=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-1024x768.jpg\" alt='' title='20241218_150249537_iOS'  height=\"768\" width=\"1024\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-1024x768.jpg 1024w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-300x225.jpg 300w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-768x576.jpg 768w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-1536x1152.jpg 1536w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-2048x1536.jpg 2048w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-1500x1125.jpg 1500w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-705x529.jpg 705w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><div  class='flex_column av-99aixk-da3fa45a621ce79e5f961dcbcea1b183 av_one_half  avia-builder-el-19  el_after_av_one_half  el_before_av_one_half  first flex_column_div  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7gqx8o-3091ba92f54c6d57f2667ec1487ed4bf\">\n.avia-image-container.av-7gqx8o-3091ba92f54c6d57f2667ec1487ed4bf img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-7gqx8o-3091ba92f54c6d57f2667ec1487ed4bf .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-7gqx8o-3091ba92f54c6d57f2667ec1487ed4bf av-styling- avia-align-center  avia-builder-el-20  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-5133 avia-img-lazy-loading-not-5133 avia_image ' src=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/Parametric-design-2-1024x768.jpg\" alt='' title='Parametric design 2'  height=\"768\" width=\"1024\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/Parametric-design-2-1024x768.jpg 1024w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/Parametric-design-2-300x225.jpg 300w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/Parametric-design-2-768x576.jpg 768w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/Parametric-design-2-1536x1152.jpg 1536w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/Parametric-design-2-2048x1536.jpg 2048w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/Parametric-design-2-1500x1125.jpg 1500w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/Parametric-design-2-705x529.jpg 705w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><\/div><div  class='flex_column av-5iuujc-81d743f09a939b7255b543993625e276 av_one_half  avia-builder-el-21  el_after_av_one_half  avia-builder-el-last  flex_column_div  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-m4wjkeea-27798e564b8911662db4cd74f88a92bb\">\n#top .av-special-heading.av-m4wjkeea-27798e564b8911662db4cd74f88a92bb{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-m4wjkeea-27798e564b8911662db4cd74f88a92bb .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-m4wjkeea-27798e564b8911662db4cd74f88a92bb .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-m4wjkeea-27798e564b8911662db4cd74f88a92bb av-special-heading-h2 blockquote modern-quote  avia-builder-el-22  el_before_av_textblock  avia-builder-el-first '><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >Automation for Smart Solutions<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-m4wjl7qa-9b9222b2504bd60eedbc41e39b065dbf '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Parametric tools are my advanced toolkit\u2014unlocking endless possibilities. I use them to enhance design processes, for example, by generating complex patterns. They also help automate parts of the engineering process, saving time while ensuring error-free and consistent results.<\/p>\n<\/div><\/section><br \/>\n<div  class='avia-buttonrow-wrap av-3lps20-24d01cb237b67b2d3a272f32519eb038 avia-buttonrow-left  avia-builder-el-24  el_after_av_textblock  avia-builder-el-last '>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2ocflk-19d1c4ae450a04041f38765793d5650f\">\n#top #wrap_all .avia-button.av-2ocflk-19d1c4ae450a04041f38765793d5650f{\nmargin-bottom:5px;\nmargin-right:5px;\n}\n<\/style>\n<a href='https:\/\/www.letolab.nl\/en\/contact\/'  class='avia-button av-2ocflk-19d1c4ae450a04041f38765793d5650f avia-icon_select-no avia-size-large avia-color-theme-color'   aria-label=\"Start Your Project\"><span class='avia_iconbox_title' >Start Your Project<\/span><\/a>\n<\/div><\/p><\/div>\n<\/p>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_3'  class='avia-section av-av_section-3226413ca2bc96f1486d7f9e0bb904ec main_color avia-section-default avia-no-border-styling  avia-builder-el-25  el_after_av_section  el_before_av_horizontal_gallery  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-5358'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-av_one_half-4236371e50272b4ec399280bbf76d6bf av_one_half  avia-builder-el-26  el_before_av_two_fifth  avia-builder-el-first  first flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-m8fzs4wt-c37deb9e5a1d63a878270a95e55b476d\">\n#top .av-special-heading.av-m8fzs4wt-c37deb9e5a1d63a878270a95e55b476d{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-m8fzs4wt-c37deb9e5a1d63a878270a95e55b476d .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-m8fzs4wt-c37deb9e5a1d63a878270a95e55b476d .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-m8fzs4wt-c37deb9e5a1d63a878270a95e55b476d av-special-heading-h2 blockquote modern-quote  avia-builder-el-27  el_before_av_textblock  avia-builder-el-first '><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >Make, Test, Improve<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-m8fzr787-2be3979341421e1441edf3edbbce6df2 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Every development process is different. Sometimes it starts with a challenging idea and an unfamiliar material, sometimes with a fully developed digital drawing. Wherever you step in, at LetoLab, you can take all the necessary steps to create something beautiful.<\/p>\n<p>Designing, experimenting, making, testing, and refining\u2014everything happens under one roof through a smooth, iterative process. Smart digital techniques such as <a href=\"https:\/\/www.letolab.nl\/en\/services\/laser-cutting-engraving\/\">laser cutting<\/a> and <a href=\"https:\/\/www.letolab.nl\/en\/services\/cam-cnc-routing\/\">CNC routing<\/a> quickly turn an idea into something tangible. Does it work right away? Great. Can it be improved? Then we adjust it. With all steps within reach, the process remains smooth and efficient. No unnecessary waiting\u2014just fast results. And that\u2019s what we love at LetoLab.<\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-5d676c9ed7be3a08936c51c97e75c1ab\">\n#top .hr.hr-invisible.av-av_hr-5d676c9ed7be3a08936c51c97e75c1ab{\nheight:100px;\n}\n<\/style>\n<div  class='hr av-av_hr-5d676c9ed7be3a08936c51c97e75c1ab hr-invisible  avia-builder-el-29  el_after_av_textblock  avia-builder-el-last '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p><\/div><div  class='flex_column av-av_two_fifth-d9d4235c4dc5477e29570d3b99e2b500 av_two_fifth  avia-builder-el-30  el_after_av_one_half  avia-builder-el-last  flex_column_div  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a\">\n#top .av-icon-circles-container.av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a{\nmargin:0 0 0 0;\nwidth:calc(100% - 0px);\npadding-bottom:calc(100% - 0px);\n}\n.av-icon-circles-container.av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a .avia-icon-circles-inner{\nborder-color:#f56c4e;\n}\n.av-icon-circles-container.av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a .avia-icon-circles-icon.active{\ncolor:#ffffff;\n}\n.av-icon-circles-container.av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a .avia-icon-circles-icon.avia-svg-icon.active svg:first-child{\nfill:#ffffff;\nstroke:#ffffff;\n}\n.av-icon-circles-container.av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a .avia-icon-circles-icon-1{\ntransform:translate(0px,250px);\nleft:50%;\ntop:0%;\n}\n.av-icon-circles-container.av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a.avia_start_animation .avia-icon-circles-icon-1{\ntransform:translate(0px,0px);\nopacity:1;\ntransition-delay:1s;\n}\n.av-icon-circles-container.av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a .avia-icon-circles-icon-2{\ntransform:translate(-216px,125px);\nleft:93%;\ntop:25%;\n}\n.av-icon-circles-container.av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a.avia_start_animation .avia-icon-circles-icon-2{\ntransform:translate(0px,0px);\nopacity:1;\ntransition-delay:1.2s;\n}\n.av-icon-circles-container.av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a .avia-icon-circles-icon-3{\ntransform:translate(-216px,-124px);\nleft:93%;\ntop:74%;\n}\n.av-icon-circles-container.av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a.avia_start_animation .avia-icon-circles-icon-3{\ntransform:translate(0px,0px);\nopacity:1;\ntransition-delay:1.4s;\n}\n.av-icon-circles-container.av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a .avia-icon-circles-icon-4{\ntransform:translate(0px,-250px);\nleft:50%;\ntop:100%;\n}\n.av-icon-circles-container.av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a.avia_start_animation .avia-icon-circles-icon-4{\ntransform:translate(0px,0px);\nopacity:1;\ntransition-delay:1.6s;\n}\n.av-icon-circles-container.av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a .avia-icon-circles-icon-5{\ntransform:translate(216px,-125px);\nleft:6%;\ntop:75%;\n}\n.av-icon-circles-container.av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a.avia_start_animation .avia-icon-circles-icon-5{\ntransform:translate(0px,0px);\nopacity:1;\ntransition-delay:1.8s;\n}\n.av-icon-circles-container.av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a .avia-icon-circles-icon-6{\ntransform:translate(216px,125px);\nleft:6%;\ntop:25%;\n}\n.av-icon-circles-container.av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a.avia_start_animation .avia-icon-circles-icon-6{\ntransform:translate(0px,0px);\nopacity:1;\ntransition-delay:2s;\n}\n.av-icon-circles-container.av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a.avia_start_animation.avia_animation_finished .avia-icon-circles-icon{\ntransition-delay:0s;\n}\n\n@media only screen and (min-width: 990px){ \n#top .av-icon-circles-container.av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a{\nmargin:0 50px 50px 50px;\nwidth:calc(100% - 100px);\npadding-bottom:calc(100% - 100px);\n}\n}\n<\/style>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-sub-av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a\">\n.av-icon-circles-container .avia-icon-circles-icon.av-av_icon_circle_item-3c0ba32e59f47cc88ba193a67a199332{\nborder-color:#f56c4e;\n}\n.av-icon-circles-container .avia-icon-circles-icon.av-av_icon_circle_item-c2b82148df1016ad33af3e68bdb7b325{\nborder-color:#f56c4e;\n}\n.av-icon-circles-container .avia-icon-circles-icon.av-av_icon_circle_item-8df7b66550ab7d65f7b56a94a706a85f{\nborder-color:#f56c4e;\n}\n.av-icon-circles-container .avia-icon-circles-icon.av-av_icon_circle_item-85c1859c50691f1a37e0c6228172e217{\nborder-color:#f56c4e;\n}\n.av-icon-circles-container .avia-icon-circles-icon.av-av_icon_circle_item-fdeb351c833dca0282245139a5f67a17{\nborder-color:#f56c4e;\n}\n.av-icon-circles-container .avia-icon-circles-icon.av-av_icon_circle_item-9cffa5321b5c008e83da64971e89aa10{\nborder-color:#f56c4e;\n}\n<\/style>\n<div class='av-icon-circles-container av-av_icon_circles-98326b287e204ce180ff9764a87a0e7a avia_animate_when_visible  avia-builder-el-31  avia-builder-el-no-sibling ' ><div class='avia-icon-circles-main-logo'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><img src='https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/11\/Lean-Startup-Cycle-achtergrond4.png' alt='' title='Lean Startup Cycle achtergrond4'  itemprop=\"thumbnailUrl\"  \/><\/div><div class=\"avia-icon-circles-inner\"><div class='avia-icon-circles-icon av-av_icon_circle_item-3c0ba32e59f47cc88ba193a67a199332 av-no-link avia-iconfont avia-font-letolab avia-icon-circles-icon-1' data-icon-circles-icon=\"1\" data-av_icon='\ue800' data-av_iconfont='letolab' ><\/div><div class='avia-icon-circles-icon-text av-av_icon_circle_item-3c0ba32e59f47cc88ba193a67a199332 avia-icon-circles-icon-text-1' data-icon-circles-text=\"1\"><div class=\"avia-icon-circles-icon-text-inner\"><div class=\"icon-title\">Design<\/div><div class=\"icon-description\"><p>Together, we refine your ideas and assess feasibility.<\/p>\n<\/div><\/div><\/div><div class='avia-icon-circles-icon av-av_icon_circle_item-c2b82148df1016ad33af3e68bdb7b325 av-no-link avia-iconfont avia-font-letolab avia-icon-circles-icon-2' data-icon-circles-icon=\"2\" data-av_icon='\ue801' data-av_iconfont='letolab' ><\/div><div class='avia-icon-circles-icon-text av-av_icon_circle_item-c2b82148df1016ad33af3e68bdb7b325 avia-icon-circles-icon-text-2' data-icon-circles-text=\"2\"><div class=\"avia-icon-circles-icon-text-inner\"><div class=\"icon-title\">Create<\/div><div class=\"icon-description\"><p>With solid preparation, the design is translated into machine-ready code and, in many cases, produced immediately. Some parts may require post-processing or assembly.<\/p>\n<\/div><\/div><\/div><div class='avia-icon-circles-icon av-av_icon_circle_item-8df7b66550ab7d65f7b56a94a706a85f av-no-link avia-iconfont avia-font-letolab avia-icon-circles-icon-3' data-icon-circles-icon=\"3\" data-av_icon='\ue802' data-av_iconfont='letolab' ><\/div><div class='avia-icon-circles-icon-text av-av_icon_circle_item-8df7b66550ab7d65f7b56a94a706a85f avia-icon-circles-icon-text-3' data-icon-circles-text=\"3\"><div class=\"avia-icon-circles-icon-text-inner\"><div class=\"icon-title\">Product<\/div><div class=\"icon-description\"><p>The result! Sometimes this is the final destination, but other times, tweaks might be needed.<\/p>\n<\/div><\/div><\/div><div class='avia-icon-circles-icon av-av_icon_circle_item-85c1859c50691f1a37e0c6228172e217 av-no-link avia-iconfont avia-font-letolab avia-icon-circles-icon-4' data-icon-circles-icon=\"4\" data-av_icon='\ue803' data-av_iconfont='letolab' ><\/div><div class='avia-icon-circles-icon-text av-av_icon_circle_item-85c1859c50691f1a37e0c6228172e217 avia-icon-circles-icon-text-4' data-icon-circles-text=\"4\"><div class=\"avia-icon-circles-icon-text-inner\"><div class=\"icon-title\">Test<\/div><div class=\"icon-description\"><p>Theory and practice don\u2019t always align\u2014that\u2019s why testing is key. This phase is all about evaluating the product and its functionality.<\/p>\n<\/div><\/div><\/div><div class='avia-icon-circles-icon av-av_icon_circle_item-fdeb351c833dca0282245139a5f67a17 av-no-link avia-iconfont avia-font-letolab avia-icon-circles-icon-5' data-icon-circles-icon=\"5\" data-av_icon='\ue804' data-av_iconfont='letolab' ><\/div><div class='avia-icon-circles-icon-text av-av_icon_circle_item-fdeb351c833dca0282245139a5f67a17 avia-icon-circles-icon-text-5' data-icon-circles-text=\"5\"><div class=\"avia-icon-circles-icon-text-inner\"><div class=\"icon-title\">Data<\/div><div class=\"icon-description\"><p>We review the findings and discuss possible improvements together.<\/p>\n<\/div><\/div><\/div><div class='avia-icon-circles-icon av-av_icon_circle_item-9cffa5321b5c008e83da64971e89aa10 av-no-link avia-iconfont avia-font-letolab avia-icon-circles-icon-6' data-icon-circles-icon=\"6\" data-av_icon='\ue805' data-av_iconfont='letolab' ><\/div><div class='avia-icon-circles-icon-text av-av_icon_circle_item-9cffa5321b5c008e83da64971e89aa10 avia-icon-circles-icon-text-6' data-icon-circles-text=\"6\"><div class=\"avia-icon-circles-icon-text-inner\"><div class=\"icon-title\">Tune<\/div><div class=\"icon-description\"><p>By now, it\u2019s often clear where refinements are needed. This is where we fine-tune the design or adjust the production process for even better results.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-denr6g-75af755330367c631502f9fb5c0e11e6\">\n.av-horizontal-gallery.av-denr6g-75af755330367c631502f9fb5c0e11e6{\npadding:3.75% 0px;;\n}\n.av-horizontal-gallery.av-denr6g-75af755330367c631502f9fb5c0e11e6 .av-horizontal-gallery-inner{\npadding-bottom:25%;\n}\n<\/style>\n<div  class='av-horizontal-gallery av-denr6g-75af755330367c631502f9fb5c0e11e6 av-horizontal-gallery-large-gap av-horizontal-gallery-enlarge-effect  avia-builder-el-32  el_after_av_section  el_before_av_section  av-slideshow-ui av-control-default av-slideshow-manual av-loop-once av-loop-manual-once av-horizontal-gallery-1' data-slideshow-data=\"{&quot;enlarge&quot;:1.3,&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-once&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:&quot;&quot;,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class='avia-slideshow-arrows avia-slideshow-controls' ><a href='#prev' class='prev-slide av-horizontal-gallery-prev avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='left-open-big' data-av_iconset='svg_entypo-fontello' tabindex='-1' title=\"Previous\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-1' aria-describedby='av-svg-desc-1' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-1'>Previous<\/title>\n<desc id='av-svg-desc-1'>Previous<\/desc>\n<path d=\"M14.464 27.84q0.832 0.832 0 1.536-0.832 0.832-1.536 0l-12.544-12.608q-0.768-0.768 0-1.6l12.544-12.608q0.704-0.832 1.536 0 0.832 0.704 0 1.536l-11.456 11.904z\"><\/path>\n<\/svg><span class='avia_hidden_link_text'>Previous<\/span><\/a><a href='#next' class='next-slide av-horizontal-gallery-next avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='right-open-big' data-av_iconset='svg_entypo-fontello' tabindex='-1' title=\"Next\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-2' aria-describedby='av-svg-desc-2' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-2'>Next<\/title>\n<desc id='av-svg-desc-2'>Next<\/desc>\n<path d=\"M0.416 27.84l11.456-11.84-11.456-11.904q-0.832-0.832 0-1.536 0.832-0.832 1.536 0l12.544 12.608q0.768 0.832 0 1.6l-12.544 12.608q-0.704 0.832-1.536 0-0.832-0.704 0-1.536z\"><\/path>\n<\/svg><span class='avia_hidden_link_text'>Next<\/span><\/a><\/div><div class='avia-slideshow-dots avia-slideshow-controls av-horizontal-gallery-dots fade-in'><a href='#1' class='goto-slide active' >1<\/a><a href='#2' class='goto-slide ' >2<\/a><a href='#3' class='goto-slide ' >3<\/a><a href='#4' class='goto-slide ' >4<\/a><a href='#5' class='goto-slide ' >5<\/a><\/div><div class='av-horizontal-gallery-inner' data-av-height='25'><div class=\"av-horizontal-gallery-slider\"><div class=\"av-horizontal-gallery-wrap noHover\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-5132 avia-img-lazy-loading-not-5132 av-horizontal-gallery-img' width=\"1024\" height=\"768\" src=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-1024x768.jpg\" title='20241218_150249537_iOS' alt='' srcset=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-1024x768.jpg 1024w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-300x225.jpg 300w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-768x576.jpg 768w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-1536x1152.jpg 1536w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-2048x1536.jpg 2048w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-1500x1125.jpg 1500w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-705x529.jpg 705w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><a href=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-1024x768.jpg\" data-srcset=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-1024x768.jpg 1024w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-300x225.jpg 300w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-768x576.jpg 768w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-1536x1152.jpg 1536w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-2048x1536.jpg 2048w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-1500x1125.jpg 1500w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241218_150249537_iOS-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" class='av-horizontal-gallery-link avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='resize-full' data-av_iconset='svg_entypo-fontello' title='3D Visualisatie' alt='' aria-label='Open image in lightbox: 20241218_150249537_iOS'><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25\" height=\"32\" viewBox=\"0 0 25 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-3' aria-describedby='av-svg-desc-3' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-3'>Open image in lightbox: 20241218_150249537_iOS<\/title>\n<desc id='av-svg-desc-3'>Open image in lightbox: 20241218_150249537_iOS<\/desc>\n<path d=\"M15.232 3.328h10.112v10.112l-3.2-3.968-4.672 4.864-3.2-3.2 4.864-4.672zM7.872 17.536l3.2 3.2-4.864 4.672 3.904 3.2h-10.112v-10.112l3.2 3.904z\"><\/path>\n<\/svg><\/a><\/div><div class=\"av-horizontal-gallery-wrap noHover\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-5153 avia-img-lazy-loading-not-5153 av-horizontal-gallery-img' width=\"1024\" height=\"771\" src=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/spatscherm1c-1024x771.jpg\" title='spatscherm1c' alt='' srcset=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/spatscherm1c-1024x771.jpg 1024w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/spatscherm1c-300x226.jpg 300w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/spatscherm1c-768x578.jpg 768w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/spatscherm1c-1536x1156.jpg 1536w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/spatscherm1c-2048x1542.jpg 2048w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/spatscherm1c-1500x1129.jpg 1500w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/spatscherm1c-705x531.jpg 705w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><a href=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/spatscherm1c-1024x771.jpg\" data-srcset=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/spatscherm1c-1024x771.jpg 1024w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/spatscherm1c-300x226.jpg 300w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/spatscherm1c-768x578.jpg 768w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/spatscherm1c-1536x1156.jpg 1536w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/spatscherm1c-2048x1542.jpg 2048w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/spatscherm1c-1500x1129.jpg 1500w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/spatscherm1c-705x531.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" class='av-horizontal-gallery-link avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='resize-full' data-av_iconset='svg_entypo-fontello' title='3D Design' alt='' aria-label='Open image in lightbox: spatscherm1c'><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25\" height=\"32\" viewBox=\"0 0 25 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-4' aria-describedby='av-svg-desc-4' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-4'>Open image in lightbox: spatscherm1c<\/title>\n<desc id='av-svg-desc-4'>Open image in lightbox: spatscherm1c<\/desc>\n<path d=\"M15.232 3.328h10.112v10.112l-3.2-3.968-4.672 4.864-3.2-3.2 4.864-4.672zM7.872 17.536l3.2 3.2-4.864 4.672 3.904 3.2h-10.112v-10.112l3.2 3.904z\"><\/path>\n<\/svg><\/a><\/div><div class=\"av-horizontal-gallery-wrap noHover\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-5129 avia-img-lazy-loading-not-5129 av-horizontal-gallery-img' width=\"1024\" height=\"768\" src=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241216_110958106_iOS-1024x768.jpg\" title='3D CAD' alt='' srcset=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241216_110958106_iOS-1024x768.jpg 1024w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241216_110958106_iOS-300x225.jpg 300w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241216_110958106_iOS-768x576.jpg 768w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241216_110958106_iOS-1536x1152.jpg 1536w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241216_110958106_iOS-2048x1536.jpg 2048w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241216_110958106_iOS-1500x1125.jpg 1500w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241216_110958106_iOS-705x529.jpg 705w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><a href=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241216_110958106_iOS-1024x768.jpg\" data-srcset=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241216_110958106_iOS-1024x768.jpg 1024w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241216_110958106_iOS-300x225.jpg 300w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241216_110958106_iOS-768x576.jpg 768w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241216_110958106_iOS-1536x1152.jpg 1536w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241216_110958106_iOS-2048x1536.jpg 2048w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241216_110958106_iOS-1500x1125.jpg 1500w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/20241216_110958106_iOS-705x529.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" class='av-horizontal-gallery-link avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='resize-full' data-av_iconset='svg_entypo-fontello' title='3D Computational Design 1' alt='' aria-label='Open image in lightbox: 3D CAD'><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25\" height=\"32\" viewBox=\"0 0 25 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-5' aria-describedby='av-svg-desc-5' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-5'>Open image in lightbox: 3D CAD<\/title>\n<desc id='av-svg-desc-5'>Open image in lightbox: 3D CAD<\/desc>\n<path d=\"M15.232 3.328h10.112v10.112l-3.2-3.968-4.672 4.864-3.2-3.2 4.864-4.672zM7.872 17.536l3.2 3.2-4.864 4.672 3.904 3.2h-10.112v-10.112l3.2 3.904z\"><\/path>\n<\/svg><\/a><\/div><div class=\"av-horizontal-gallery-wrap noHover\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-5146 avia-img-lazy-loading-not-5146 av-horizontal-gallery-img' width=\"1024\" height=\"691\" src=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/computational-design1-1024x691.jpg\" title='computational design1' alt='' srcset=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/computational-design1-1024x691.jpg 1024w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/computational-design1-300x202.jpg 300w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/computational-design1-768x518.jpg 768w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/computational-design1-705x476.jpg 705w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/computational-design1.jpg 1249w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><a href=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/computational-design1-1024x691.jpg\" data-srcset=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/computational-design1-1024x691.jpg 1024w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/computational-design1-300x202.jpg 300w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/computational-design1-768x518.jpg 768w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/computational-design1-705x476.jpg 705w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/12\/computational-design1.jpg 1249w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" class='av-horizontal-gallery-link avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='resize-full' data-av_iconset='svg_entypo-fontello' title='3D Computational Design 2' alt='' aria-label='Open image in lightbox: computational design1'><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25\" height=\"32\" viewBox=\"0 0 25 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-6' aria-describedby='av-svg-desc-6' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-6'>Open image in lightbox: computational design1<\/title>\n<desc id='av-svg-desc-6'>Open image in lightbox: computational design1<\/desc>\n<path d=\"M15.232 3.328h10.112v10.112l-3.2-3.968-4.672 4.864-3.2-3.2 4.864-4.672zM7.872 17.536l3.2 3.2-4.864 4.672 3.904 3.2h-10.112v-10.112l3.2 3.904z\"><\/path>\n<\/svg><\/a><\/div><div class=\"av-horizontal-gallery-wrap noHover\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-5195 avia-img-lazy-loading-not-5195 av-horizontal-gallery-img' width=\"1024\" height=\"683\" src=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/render-5-2-1024x683.jpg\" title='Hand Boekenkast 1' alt='' srcset=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/render-5-2-1024x683.jpg 1024w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/render-5-2-300x200.jpg 300w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/render-5-2-768x512.jpg 768w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/render-5-2-1536x1024.jpg 1536w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/render-5-2-2048x1365.jpg 2048w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/render-5-2-1500x1000.jpg 1500w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/render-5-2-705x470.jpg 705w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><a href=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/render-5-2-1024x683.jpg\" data-srcset=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/render-5-2-1024x683.jpg 1024w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/render-5-2-300x200.jpg 300w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/render-5-2-768x512.jpg 768w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/render-5-2-1536x1024.jpg 1536w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/render-5-2-2048x1365.jpg 2048w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/render-5-2-1500x1000.jpg 1500w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/render-5-2-705x470.jpg 705w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" class='av-horizontal-gallery-link avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='resize-full' data-av_iconset='svg_entypo-fontello' title='3D Computational Design 3' alt='' aria-label='Open image in lightbox: Hand Boekenkast 1'><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25\" height=\"32\" viewBox=\"0 0 25 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-7' aria-describedby='av-svg-desc-7' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-7'>Open image in lightbox: Hand Boekenkast 1<\/title>\n<desc id='av-svg-desc-7'>Open image in lightbox: Hand Boekenkast 1<\/desc>\n<path d=\"M15.232 3.328h10.112v10.112l-3.2-3.968-4.672 4.864-3.2-3.2 4.864-4.672zM7.872 17.536l3.2 3.2-4.864 4.672 3.904 3.2h-10.112v-10.112l3.2 3.904z\"><\/path>\n<\/svg><\/a><\/div><\/div><\/div><\/div>\n<div id='av_section_4'  class='avia-section av-5peeh4-49cc03d141fee2e5710774892cd0bec2 main_color avia-section-default avia-no-border-styling  avia-builder-el-33  el_after_av_horizontal_gallery  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-5358'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-3jyjtk-937eb9cc5d79c650393e6bb173610a09 av_one_full  avia-builder-el-34  avia-builder-el-no-sibling  first flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-m6qnh0k9-14328570f86d36b5e2331a6ebdd27c42\">\n#top .av-special-heading.av-m6qnh0k9-14328570f86d36b5e2331a6ebdd27c42{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-m6qnh0k9-14328570f86d36b5e2331a6ebdd27c42 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-m6qnh0k9-14328570f86d36b5e2331a6ebdd27c42 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-m6qnh0k9-14328570f86d36b5e2331a6ebdd27c42 av-special-heading-h2 blockquote modern-quote modern-centered  avia-builder-el-35  el_before_av_blog  avia-builder-el-first '><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >Projects<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<div  data-slideshow-options=\"{&quot;animation&quot;:&quot;fade&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;show_slide_delay&quot;:90}\" class='avia-content-slider avia-content-grid-active avia-content-slider1 avia-content-slider-odd  avia-builder-el-36  el_after_av_heading  el_before_av_buttonrow  av-slideshow-ui av-control-default   av-no-slider-navigation av-slideshow-manual av-loop-once av-loop-manual-endless '  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Blog\" ><div class=\"avia-content-slider-inner\"><div class=\"slide-entry-wrap\"><article class='slide-entry flex_column  post-entry post-entry-6218 slide-entry-overview slide-loop-1 slide-parity-odd  av_one_third first real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/www.letolab.nl\/en\/decoratief-wandpaneel-2\/' data-rel='slide-1' class='slide-image' title='Decorative Wall Panel'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/custom-wanddecoratie4-495x400.jpg\" class=\"wp-image-5229 avia-img-lazy-loading-not-5229 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/custom-wanddecoratie4-495x400.jpg 495w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/custom-wanddecoratie4-845x684.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Decorative Wall Panel\"><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.letolab.nl\/en\/decoratief-wandpaneel-2\/' title='Decorative Wall Panel'>Decorative Wall Panel<\/a><\/h3><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/www.letolab.nl\/en\/category\/technieken-en\/cad-digitaal-tekenwerk-en\/\" rel=\"tag\">CAD-Digitaal tekenwerk<\/a>, <a href=\"https:\/\/www.letolab.nl\/en\/category\/technieken-en\/cnc-frezen-en\/\" rel=\"tag\">CNC Frezen<\/a>, <a href=\"https:\/\/www.letolab.nl\/en\/category\/in_opdracht_samenwerking-en\/design-en\/\" rel=\"tag\">Design<\/a>, <a href=\"https:\/\/www.letolab.nl\/en\/category\/materialen-en\/hout-en\/\" rel=\"tag\">Hout<\/a>, <a href=\"https:\/\/www.letolab.nl\/en\/category\/in_opdracht_samenwerking-en\/\" rel=\"tag\">In Opdracht \/ Samenwerking<\/a>, <a href=\"https:\/\/www.letolab.nl\/en\/category\/technieken-en\/maatwerk-computational-design-en\/\" rel=\"tag\">Maatwerk &amp; Computational Design<\/a>, <a href=\"https:\/\/www.letolab.nl\/en\/category\/eigenwerk-en\/wanddecoratie-en-eigenwerk-en\/\" rel=\"tag\">Wanddecoratie<\/a> <\/span><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" >Wall Panel\u2014Cut from a Single Sheet with Clever CNC Techniques<\/div><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2025-02-14T11:48:56+01:00\" >14 February 2025<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/custom-wanddecoratie4.jpg<\/span>\n\t\t\t\t\t\t<span itemprop='height'>2526<\/span>\n\t\t\t\t\t\t<span itemprop='width'>2540<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>efienieg<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/06\/LetoLab-logo.svg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>efienieg<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2024-06-11T16:47:56+02:00\" >2025-02-14 11:48:56<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2025-03-19 19:29:31<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Decorative Wall Panel<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-5766 slide-entry-overview slide-loop-2 slide-parity-even  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/www.letolab.nl\/en\/cnc-cut-kitchen\/' data-rel='slide-1' class='slide-image' title='CNC-Cut Kitchen'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/02\/IMG_20250129_105415-3-495x400.jpg\" class=\"wp-image-5677 avia-img-lazy-loading-not-5677 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/02\/IMG_20250129_105415-3-495x400.jpg 495w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/02\/IMG_20250129_105415-3-845x684.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: CNC-Cut Kitchen\"><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.letolab.nl\/en\/cnc-cut-kitchen\/' title='CNC-Cut Kitchen'>CNC-Cut Kitchen<\/a><\/h3><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/www.letolab.nl\/en\/category\/in_opdracht_samenwerking-en\/bouwpakketten-coproduced-en\/\" rel=\"tag\">Bouwpakketten<\/a>, <a href=\"https:\/\/www.letolab.nl\/en\/category\/technieken-en\/cad-digitaal-tekenwerk-en\/\" rel=\"tag\">CAD-Digitaal tekenwerk<\/a>, <a href=\"https:\/\/www.letolab.nl\/en\/category\/technieken-en\/cnc-frezen-en\/\" rel=\"tag\">CNC Frezen<\/a>, <a href=\"https:\/\/www.letolab.nl\/en\/category\/materialen-en\/hout-en\/\" rel=\"tag\">Hout<\/a>, <a href=\"https:\/\/www.letolab.nl\/en\/category\/in_opdracht_samenwerking-en\/\" rel=\"tag\">In Opdracht \/ Samenwerking<\/a>, <a href=\"https:\/\/www.letolab.nl\/en\/category\/technieken-en\/maatwerk-computational-design-en\/\" rel=\"tag\">Maatwerk &amp; Computational Design<\/a> <\/span><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" >A complete building kit for a custom kitchen, entirely fabricated with CNC techniques<\/div><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2025-02-07T21:46:07+01:00\" >7 February 2025<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/02\/IMG_20250129_105415-3.jpg<\/span>\n\t\t\t\t\t\t<span itemprop='height'>1920<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1440<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>efienieg<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/06\/LetoLab-logo.svg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>efienieg<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2024-06-11T16:47:56+02:00\" >2025-02-07 21:46:07<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2025-03-25 12:41:35<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>CNC-Cut Kitchen<\/span><\/span><\/span><\/article><article class='slide-entry flex_column  post-entry post-entry-5768 slide-entry-overview slide-loop-3 slide-parity-odd  post-entry-last  av_one_third  real-thumbnail posttype-post post-format-standard'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href='https:\/\/www.letolab.nl\/en\/sliced-face\/' data-rel='slide-1' class='slide-image' title='Sliced Face'><img decoding=\"async\" fetchpriority=\"high\" width=\"495\" height=\"400\" src=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/20240617_162959000_iOS-e1736784272273-495x400.jpg\" class=\"wp-image-5304 avia-img-lazy-loading-not-5304 attachment-portfolio size-portfolio wp-post-image\" alt=\"\" srcset=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/20240617_162959000_iOS-e1736784272273-495x400.jpg 495w, https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/20240617_162959000_iOS-e1736784272273-845x684.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/a><div class=\"slide-content\"><header class=\"entry-content-header\" aria-label=\"Slide: Sliced Face\"><h3 class='slide-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.letolab.nl\/en\/sliced-face\/' title='Sliced Face'>Sliced Face<\/a><\/h3><span class=\"blog-categories minor-meta\"><a href=\"https:\/\/www.letolab.nl\/en\/category\/technieken-en\/cad-digitaal-tekenwerk-en\/\" rel=\"tag\">CAD-Digitaal tekenwerk<\/a>, <a href=\"https:\/\/www.letolab.nl\/en\/category\/in_opdracht_samenwerking-en\/design-en\/\" rel=\"tag\">Design<\/a>, <a href=\"https:\/\/www.letolab.nl\/en\/category\/materialen-en\/hout-en\/\" rel=\"tag\">Hout<\/a>, <a href=\"https:\/\/www.letolab.nl\/en\/category\/in_opdracht_samenwerking-en\/\" rel=\"tag\">In Opdracht \/ Samenwerking<\/a>, <a href=\"https:\/\/www.letolab.nl\/en\/category\/technieken-en\/lasersnijden-en\/\" rel=\"tag\">Lasersnijden<\/a>, <a href=\"https:\/\/www.letolab.nl\/en\/category\/technieken-en\/maatwerk-computational-design-en\/\" rel=\"tag\">Maatwerk &amp; Computational Design<\/a>, <a href=\"https:\/\/www.letolab.nl\/en\/category\/in_opdracht_samenwerking-en\/sculpturen-coproduced-en\/\" rel=\"tag\">Sculpturen<\/a> <\/span><span class=\"av-vertical-delimiter\"><\/span><\/header><div class='slide-entry-excerpt entry-content'  itemprop=\"text\" >Layered sculpture for a future-focused installation, parametrically cut.<\/div><\/div><footer class=\"entry-footer\"><div class=\"slide-meta\"><time class='slide-meta-time updated'  itemprop=\"datePublished\" datetime=\"2025-01-13T15:32:52+01:00\" >13 January 2025<\/time><\/div><\/footer><span class='hidden'>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" >\n\t\t\t\t\t\t<span itemprop='url'>https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/01\/20240617_162959000_iOS-e1736784272273.jpg<\/span>\n\t\t\t\t\t\t<span itemprop='height'>1536<\/span>\n\t\t\t\t\t\t<span itemprop='width'>1536<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class='av-structured-data'  itemprop=\"publisher\" itemtype=\"https:\/\/schema.org\/Organization\" itemscope=\"itemscope\" >\n\t\t\t\t\t\t<span itemprop='name'>efienieg<\/span>\n\t\t\t\t\t\t<span itemprop='logo' itemscope itemtype='https:\/\/schema.org\/ImageObject'>\n\t\t\t\t\t\t\t<span itemprop='url'>https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/06\/LetoLab-logo.svg<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t<\/span><span class='av-structured-data'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><span itemprop='name'>efienieg<\/span><\/span><span class='av-structured-data'  itemprop=\"datePublished\" datetime=\"2024-06-11T16:47:56+02:00\" >2025-01-13 15:32:52<\/span><span class='av-structured-data'  itemprop=\"dateModified\" itemtype=\"https:\/\/schema.org\/dateModified\" >2025-03-19 19:32:00<\/span><span class='av-structured-data'  itemprop=\"mainEntityOfPage\" itemtype=\"https:\/\/schema.org\/mainEntityOfPage\" ><span itemprop='name'>Sliced Face<\/span><\/span><\/span><\/article><\/div><\/div><\/div><br \/>\n<div  class='avia-buttonrow-wrap av-m6qnoz3x-c43cb58af15395ee64cbc725202dd246 avia-buttonrow-center  avia-builder-el-37  el_after_av_blog  avia-builder-el-last '>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-m6qnoyk7-a64c744e5d83b45c00fd3250665369f5\">\n#top #wrap_all .avia-button.av-m6qnoyk7-a64c744e5d83b45c00fd3250665369f5{\nmargin-bottom:5px;\nmargin-right:3px;\nmargin-left:3px;\n}\n<\/style>\n<a href='https:\/\/www.letolab.nl\/en\/projects\/'  class='avia-button av-m6qnoyk7-a64c744e5d83b45c00fd3250665369f5 avia-icon_select-no avia-size-large avia-color-theme-color'   aria-label=\"More Projects\"><span class='avia_iconbox_title' >More Projects<\/span><\/a>\n<\/div><\/p><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_5'  class='avia-section av-cw3gjc-851c1f15a44e79a83f18839974495424 main_color avia-section-default avia-no-border-styling  avia-builder-el-38  el_after_av_section  el_before_av_custom_layout  avia-bg-style-scroll av-minimum-height av-minimum-height-custom av-height-custom  container_wrap fullsize'   data-av_minimum_height_px='500'><div class='container av-section-cont-open' style='height:500px'><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-5358'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-bet5w8-81985977700316593ac2f1a9a288287e av_one_fifth  avia-builder-el-39  el_before_av_three_fifth  avia-builder-el-first  first av-break-at-tablet flex_column_div  '     ><\/div><div  class='flex_column av-8wz2fc-5ac1541d102fd20dcec0a773c85727fc av_three_fifth  avia-builder-el-40  el_after_av_one_fifth  el_before_av_one_fifth  av-break-at-tablet flex_column_div  '     ><div  class='avia-testimonial-wrapper av-788uq0-5ec9be5db238f4d5f9532beb7ae68556 avia-slider-testimonials avia-slider-2-testimonials avia_animate_when_almost_visible av-slideshow-ui av-control-hidden av-no-slider-navigation av-hide-nav-arrows av-slider-hover-pause av-slideshow-autoplay av-loop-endless av-loop-manual-endless' data-slideshow-options=\"{&quot;animation&quot;:&quot;fade&quot;,&quot;autoplay&quot;:true,&quot;loop_autoplay&quot;:&quot;endless&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:true,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:&quot;&quot;,&quot;hoverpause&quot;:true,&quot;show_slide_delay&quot;:0}\">\n<section class=\"avia-testimonial-row\"><div class='avia-testimonial av-luoe0-c94ccab6bbd93f92d137f9be3d664d58 avia-testimonial-row-1 avia-first-testimonial flex_column no_margin av_one_half'><div class='avia-testimonial_inner'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia-testimonial-content '><div class='avia-testimonial-markup-entry-content'  itemprop=\"text\" ><\/div><\/div><div class=\"avia-testimonial-meta\"><div class=\"avia-testimonial-arrow-wrap\"><div class=\"avia-arrow\"><\/div><\/div><div class='avia-testimonial-meta-mini'  itemprop=\"author\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\" ><\/div><\/div><\/div><\/div>\n<\/section><div class='avia-slideshow-arrows avia-slideshow-controls' ><a href='#prev' class='prev-slide  avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='left-open-big' data-av_iconset='svg_entypo-fontello' tabindex='-1' title=\"Previous\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-11' aria-describedby='av-svg-desc-11' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-11'>Previous<\/title>\n<desc id='av-svg-desc-11'>Previous<\/desc>\n<path d=\"M14.464 27.84q0.832 0.832 0 1.536-0.832 0.832-1.536 0l-12.544-12.608q-0.768-0.768 0-1.6l12.544-12.608q0.704-0.832 1.536 0 0.832 0.704 0 1.536l-11.456 11.904z\"><\/path>\n<\/svg><span class='avia_hidden_link_text'>Previous<\/span><\/a><a href='#next' class='next-slide  avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='right-open-big' data-av_iconset='svg_entypo-fontello' tabindex='-1' title=\"Next\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-12' aria-describedby='av-svg-desc-12' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-12'>Next<\/title>\n<desc id='av-svg-desc-12'>Next<\/desc>\n<path d=\"M0.416 27.84l11.456-11.84-11.456-11.904q-0.832-0.832 0-1.536 0.832-0.832 1.536 0l12.544 12.608q0.768 0.832 0 1.6l-12.544 12.608q-0.704 0.832-1.536 0-0.832-0.704 0-1.536z\"><\/path>\n<\/svg><span class='avia_hidden_link_text'>Next<\/span><\/a><\/div><\/div><\/div><div  class='flex_column av-4w4ay0-19d08cf7d4f98a738b8fe00037c039b4 av_one_fifth  avia-builder-el-42  el_after_av_three_fifth  avia-builder-el-last  av-break-at-tablet flex_column_div  '     ><\/div>\n\n\n[av_section min_height='' min_height_pc='25' min_height_px='500px' shadow='no-border-styling' bottom_border='no-border-styling' bottom_border_diagonal_color='#333333' bottom_border_diagonal_direction='' bottom_border_style='' padding='default' margin='' custom_margin='0px' av-desktop-custom_margin='' av-medium-custom_margin='' av-small-custom_margin='' av-mini-custom_margin='' svg_div_top='' svg_div_top_color='#333333' svg_div_top_width='100' svg_div_top_height='50' svg_div_top_max_height='none' svg_div_top_flip='' svg_div_top_invert='' svg_div_top_front='' svg_div_top_opacity='' svg_div_top_preview='' svg_div_bottom='' svg_div_bottom_color='#333333' svg_div_bottom_width='100' svg_div_bottom_height='50' svg_div_bottom_max_height='none' svg_div_bottom_flip='' svg_div_bottom_invert='' svg_div_bottom_front='' svg_div_bottom_opacity='' svg_div_bottom_preview='' fold_type='' fold_height='' fold_more='Lees meer' fold_less='Lees minder' fold_text_style='' fold_btn_align='' color='main_color' background='bg_color' custom_bg='' background_gradient_direction='vertical' background_gradient_color1='#000000' background_gradient_color2='#ffffff' background_gradient_color3='' src='' src_dynamic='' attach='scroll' position='top left' repeat='no-repeat' video='' video_ratio='16:9' video_mobile_disabled='' overlay_enable='' overlay_opacity='0.5' overlay_color='' overlay_pattern='' overlay_custom_pattern='' scroll_down='' custom_arrow_bg='' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' fold_timer='' z_index_fold='' css_position_z_index='' av-desktop-css_position_z_index='' av-medium-css_position_z_index='' av-small-css_position_z_index='' av-mini-css_position_z_index='' av-desktop-hide='' av-medium-hide='' av-small-hide='' av-mini-hide='' id='' custom_class='' template_class='' aria_label='' av_element_hidden_in_editor='0' av_uid='av-f2bedw' sc_version='1.0']\n\n[av_one_fourth first min_height='' vertical_alignment='av-align-top' space='' row_boxshadow_width='10' row_boxshadow_color='' margin='0px' margin_sync='true' av-desktop-margin='' av-desktop-margin_sync='true' av-medium-margin='' av-medium-margin_sync='true' av-small-margin='' av-small-margin_sync='true' av-mini-margin='' av-mini-margin_sync='true' mobile_breaking='av-break-at-tablet' mobile_column_order='' border='' border_style='solid' border_color='' radius='' radius_sync='true' min_col_height='' padding='' padding_sync='true' av-desktop-padding='' av-desktop-padding_sync='true' av-medium-padding='' av-medium-padding_sync='true' av-small-padding='' av-small-padding_sync='true' av-mini-padding='' av-mini-padding_sync='true' svg_div_top='' svg_div_top_color='#333333' svg_div_top_width='100' svg_div_top_height='50' svg_div_top_max_height='none' svg_div_top_opacity='' svg_div_bottom='' svg_div_bottom_color='#333333' svg_div_bottom_width='100' svg_div_bottom_height='50' svg_div_bottom_max_height='none' svg_div_bottom_opacity='' fold_type='' fold_height='' fold_more='Lees meer' fold_less='Lees minder' fold_text_style='' fold_btn_align='' column_boxshadow_width='10' column_boxshadow_color='' background='bg_color' background_color='' background_gradient_direction='vertical' background_gradient_color1='#000000' background_gradient_color2='#ffffff' background_gradient_color3='' src='' attachment='' attachment_size='' src_dynamic='' background_position='top left' background_repeat='no-repeat' highlight_size='1.1' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' animation='' animation_duration='' animation_custom_bg_color='' animation_z_index_curtain='100' parallax_parallax='' parallax_parallax_speed='' av-desktop-parallax_parallax='' av-desktop-parallax_parallax_speed='' av-medium-parallax_parallax='' av-medium-parallax_parallax_speed='' av-small-parallax_parallax='' av-small-parallax_parallax_speed='' av-mini-parallax_parallax='' av-mini-parallax_parallax_speed='' fold_timer='' z_index_fold='' css_position='' css_position_location=',,,' css_position_z_index='' av-desktop-css_position='' av-desktop-css_position_location=',,,' av-desktop-css_position_z_index='' av-medium-css_position='' av-medium-css_position_location=',,,' av-medium-css_position_z_index='' av-small-css_position='' av-small-css_position_location=',,,' av-small-css_position_z_index='' av-mini-css_position='' av-mini-css_position_location=',,,' av-mini-css_position_z_index='' link='' link_dynamic='' linktarget='' link_hover='' title_attr='' alt_attr='' mobile_display='' mobile_col_pos='0' id='' custom_class='' template_class='' aria_label='' av_uid='av-etqjk4' sc_version='1.0']\n\n[av_image src='https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/09\/Portret-contact.jpg' attachment='3541' attachment_size='full' src_dynamic='' copyright='' caption='' image_size='' styling='' box_shadow='none' box_shadow_width='10' box_shadow_color='' align='left' font_size='' overlay_opacity='0.4' overlay_color='#000000' overlay_text_color='#ffffff' link='' link_dynamic='' target='' animation='no-animation' animation_duration='' animation_custom_bg_color='' animation_z_index_curtain='100' parallax_parallax='' parallax_parallax_speed='' av-desktop-parallax_parallax='' av-desktop-parallax_parallax_speed='' av-medium-parallax_parallax='' av-medium-parallax_parallax_speed='' av-small-parallax_parallax='' av-small-parallax_parallax_speed='' av-mini-parallax_parallax='' av-mini-parallax_parallax_speed='' hover='' blur_image='' grayscale_image='' fade_image='' appearance='' css_position='' css_position_location=',,,' css_position_z_index='' av-desktop-css_position='' av-desktop-css_position_location=',,,' av-desktop-css_position_z_index='' av-medium-css_position='' av-medium-css_position_location=',,,' av-medium-css_position_z_index='' av-small-css_position='' av-small-css_position_location=',,,' av-small-css_position_z_index='' av-mini-css_position='' av-mini-css_position_location=',,,' av-mini-css_position_z_index='' transform_perspective='' transform_rotation=',,,' transform_scale=',,' transform_skew=',' transform_translate=',,' av-desktop-transform_perspective='' av-desktop-transform_rotation=',,,' av-desktop-transform_scale=',,' av-desktop-transform_skew=',' av-desktop-transform_translate=',,' av-medium-transform_perspective='' av-medium-transform_rotation=',,,' av-medium-transform_scale=',,' av-medium-transform_skew=',' av-medium-transform_translate=',,' av-small-transform_perspective='' av-small-transform_rotation=',,,' av-small-transform_scale=',,' av-small-transform_skew=',' av-small-transform_translate=',,' av-mini-transform_perspective='' av-mini-transform_rotation=',,,' av-mini-transform_scale=',,' av-mini-transform_skew=',' av-mini-transform_translate=',,' mask_overlay='' mask_overlay_shape='blob' mask_overlay_size='contain' mask_overlay_scale='100%' mask_overlay_position='center center' mask_overlay_repeat='no-repeat' mask_overlay_rotate='' mask_overlay_rad_shape='circle' mask_overlay_rad_position='center center' mask_overlay_opacity1='0' mask_overlay_opacity2='1' mask_overlay_opacity3='' title_attr='' alt_attr='' img_scrset='' lazy_loading='disabled' id='' custom_class='' template_class='' av_element_hidden_in_editor='0' av_uid='av-cfxrkk' sc_version='1.0' admin_preview_bg=''][\/av_image]\n\n[av_hr class='invisible' icon_select='yes' icon='ue808' font='entypo-fontello' position='center' shadow='no-shadow' height='0' custom_border='av-border-thin' custom_width='50px' custom_margin_top='30px' custom_margin_bottom='30px' custom_border_color='' custom_icon_color='' id='' custom_class='' template_class='' av_uid='av-m5zdmp5r' sc_version='1.0' admin_preview_bg='']\n\n[av_heading heading='Erwin Fienieg' tag='h3' style='blockquote modern-quote' subheading_active='' show_icon='' icon='ue800' font='entypo-fontello' size='' av-desktop-font-size-title='' av-medium-font-size-title='' av-small-font-size-title='' av-mini-font-size-title='' subheading_size='' av-desktop-font-size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' icon_size='' av-desktop-font-size-1='' av-medium-font-size-1='' av-small-font-size-1='' av-mini-font-size-1='' color='' custom_font='' subheading_color='' seperator_color='' icon_color='' margin='' margin_sync='true' av-desktop-margin='' av-desktop-margin_sync='true' av-medium-margin='' av-medium-margin_sync='true' av-small-margin='' av-small-margin_sync='true' av-mini-margin='' av-mini-margin_sync='true' headline_padding='' headline_padding_sync='true' av-desktop-headline_padding='' av-desktop-headline_padding_sync='true' av-medium-headline_padding='' av-medium-headline_padding_sync='true' av-small-headline_padding='' av-small-headline_padding_sync='true' av-mini-headline_padding='' av-mini-headline_padding_sync='true' padding='10' av-desktop-padding='' av-medium-padding='' av-small-padding='' av-mini-padding='' icon_padding='10' av-desktop-icon_padding='' av-medium-icon_padding='' av-small-icon_padding='' av-mini-icon_padding='' link='' link_dynamic='' link_target='' title_attr='' id='' custom_class='' template_class='' av_uid='av-aqnm9w' sc_version='1.0' admin_preview_bg=''][\/av_heading]\n\n[av_textblock fold_type='' fold_height='' fold_more='Lees meer' fold_less='Lees minder' fold_text_style='' fold_btn_align='' textblock_styling_align='' textblock_styling='' textblock_styling_gap='' textblock_styling_mobile='' size='' av-desktop-font-size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' font_color='' color='' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' fold_timer='' z_index_fold='' id='' custom_class='' template_class='' av_uid='av-9frqdw' sc_version='1.0' admin_preview_bg='']\n<a href=\"mailto:info@letolab.nl\">info@letolab.nl<\/a>\n<a href=\"tel:+31610595920\">+31 6 10595920<\/a>\n<a href=\"https:\/\/wa.me\/31610595920\">Whatsapp (business)<\/a>\n[\/av_textblock]\n\n[\/av_one_fourth][av_one_half min_height='' vertical_alignment='av-align-top' space='' row_boxshadow='' row_boxshadow_width='10' row_boxshadow_color='' custom_margin='' margin='0px' av-desktop-margin='' av-medium-margin='' av-small-margin='' av-mini-margin='' mobile_breaking='' mobile_column_order='' border='' border_style='solid' border_color='' radius='' min_col_height='' padding='' av-desktop-padding='' av-medium-padding='' av-small-padding='' av-mini-padding='' svg_div_top='' svg_div_top_color='#333333' svg_div_top_width='100' svg_div_top_height='50' svg_div_top_max_height='none' svg_div_top_flip='' svg_div_top_invert='' svg_div_top_front='' svg_div_top_opacity='' svg_div_top_preview='' svg_div_bottom='' svg_div_bottom_color='#333333' svg_div_bottom_width='100' svg_div_bottom_height='50' svg_div_bottom_max_height='none' svg_div_bottom_flip='' svg_div_bottom_invert='' svg_div_bottom_front='' svg_div_bottom_opacity='' svg_div_bottom_preview='' fold_type='' fold_height='' fold_more='Lees meer' fold_less='Lees minder' fold_text_style='' fold_btn_align='' column_boxshadow='' column_boxshadow_width='10' column_boxshadow_color='' background='bg_color' background_color='' background_gradient_direction='vertical' background_gradient_color1='#000000' background_gradient_color2='#ffffff' background_gradient_color3='' src='' src_dynamic='' background_position='top left' background_repeat='no-repeat' highlight='' highlight_size='' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' animation='' animation_duration='' animation_custom_bg_color='' animation_z_index_curtain='100' parallax_parallax='' parallax_parallax_speed='' av-desktop-parallax_parallax='' av-desktop-parallax_parallax_speed='' av-medium-parallax_parallax='' av-medium-parallax_parallax_speed='' av-small-parallax_parallax='' av-small-parallax_parallax_speed='' av-mini-parallax_parallax='' av-mini-parallax_parallax_speed='' fold_timer='' z_index_fold='' css_position='' css_position_location='' css_position_z_index='' av-desktop-css_position='' av-desktop-css_position_location='' av-desktop-css_position_z_index='' av-medium-css_position='' av-medium-css_position_location='' av-medium-css_position_z_index='' av-small-css_position='' av-small-css_position_location='' av-small-css_position_z_index='' av-mini-css_position='' av-mini-css_position_location='' av-mini-css_position_z_index='' link='' link_dynamic='' linktarget='' link_hover='' title_attr='' alt_attr='' mobile_display='' mobile_col_pos='0' id='' custom_class='' template_class='' aria_label='' av_uid='av-89c63o' sc_version='1.0']\n\n[av_heading heading='Contact' tag='h2' style='blockquote modern-quote' subheading_active='' show_icon='' icon='ue800' font='entypo-fontello' size='' av-desktop-font-size-title='' av-medium-font-size-title='' av-small-font-size-title='' av-mini-font-size-title='' subheading_size='' av-desktop-font-size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' icon_size='' av-desktop-font-size-1='' av-medium-font-size-1='' av-small-font-size-1='' av-mini-font-size-1='' color='' custom_font='' subheading_color='' seperator_color='' icon_color='' margin='' margin_sync='true' av-desktop-margin='' av-desktop-margin_sync='true' av-medium-margin='' av-medium-margin_sync='true' av-small-margin='' av-small-margin_sync='true' av-mini-margin='' av-mini-margin_sync='true' headline_padding='' headline_padding_sync='true' av-desktop-headline_padding='' av-desktop-headline_padding_sync='true' av-medium-headline_padding='' av-medium-headline_padding_sync='true' av-small-headline_padding='' av-small-headline_padding_sync='true' av-mini-headline_padding='' av-mini-headline_padding_sync='true' padding='10' av-desktop-padding='' av-medium-padding='' av-small-padding='' av-mini-padding='' icon_padding='10' av-desktop-icon_padding='' av-medium-icon_padding='' av-small-icon_padding='' av-mini-icon_padding='' link='' link_dynamic='' link_target='' title_attr='' id='' custom_class='' template_class='' av_uid='av-6k6b4k' sc_version='1.0' admin_preview_bg=''][\/av_heading]\n\n[av_textblock fold_type='' fold_height='' fold_more='Lees meer' fold_less='Lees minder' fold_text_style='' fold_btn_align='' textblock_styling_align='' textblock_styling='' textblock_styling_gap='' textblock_styling_mobile='' size='' av-desktop-font-size='' av-medium-font-size='' av-small-font-size='' av-mini-font-size='' font_color='' color='' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' fold_timer='' z_index_fold='' id='' custom_class='' template_class='' av_uid='av-m17xh293' sc_version='1.0' admin_preview_bg='']\nI am Erwin, founder of Letolab, maker \/ designer with a fascination for technology and digital craftsmanship. I'm happy to help you realize your ideas.\n[\/av_textblock]\n\n[av_codeblock wrapper_element='' wrapper_element_attributes='' codeblock_type='' alb_description='' id='' custom_class='' template_class='' av_uid='av-4gq1ms' sc_version='1.0']\n[gravityforms id=\"2\" title=\"false\" description=\"false\"]\n[\/av_codeblock]\n\n[\/av_one_half][av_one_fourth min_height='' vertical_alignment='av-align-top' space='' row_boxshadow='' row_boxshadow_width='10' row_boxshadow_color='' custom_margin='' margin='0px' av-desktop-margin='' av-medium-margin='' av-small-margin='' av-mini-margin='' mobile_breaking='' mobile_column_order='' border='' border_style='solid' border_color='' radius='' min_col_height='' padding='' av-desktop-padding='' av-medium-padding='' av-small-padding='' av-mini-padding='' svg_div_top='' svg_div_top_color='#333333' svg_div_top_width='100' svg_div_top_height='50' svg_div_top_max_height='none' svg_div_top_flip='' svg_div_top_invert='' svg_div_top_front='' svg_div_top_opacity='' svg_div_top_preview='' svg_div_bottom='' svg_div_bottom_color='#333333' svg_div_bottom_width='100' svg_div_bottom_height='50' svg_div_bottom_max_height='none' svg_div_bottom_flip='' svg_div_bottom_invert='' svg_div_bottom_front='' svg_div_bottom_opacity='' svg_div_bottom_preview='' fold_type='' fold_height='' fold_more='Lees meer' fold_less='Lees minder' fold_text_style='' fold_btn_align='' column_boxshadow='' column_boxshadow_width='10' column_boxshadow_color='' background='bg_color' background_color='' background_gradient_direction='vertical' background_gradient_color1='#000000' background_gradient_color2='#ffffff' background_gradient_color3='' src='' src_dynamic='' background_position='top left' background_repeat='no-repeat' highlight='' highlight_size='' fold_overlay_color='' fold_text_color='' fold_btn_color='theme-color' fold_btn_bg_color='' fold_btn_font_color='' size-btn-text='' av-desktop-font-size-btn-text='' av-medium-font-size-btn-text='' av-small-font-size-btn-text='' av-mini-font-size-btn-text='' animation='' animation_duration='' animation_custom_bg_color='' animation_z_index_curtain='100' parallax_parallax='' parallax_parallax_speed='' av-desktop-parallax_parallax='' av-desktop-parallax_parallax_speed='' av-medium-parallax_parallax='' av-medium-parallax_parallax_speed='' av-small-parallax_parallax='' av-small-parallax_parallax_speed='' av-mini-parallax_parallax='' av-mini-parallax_parallax_speed='' fold_timer='' z_index_fold='' css_position='' css_position_location='' css_position_z_index='' av-desktop-css_position='' av-desktop-css_position_location='' av-desktop-css_position_z_index='' av-medium-css_position='' av-medium-css_position_location='' av-medium-css_position_z_index='' av-small-css_position='' av-small-css_position_location='' av-small-css_position_z_index='' av-mini-css_position='' av-mini-css_position_location='' av-mini-css_position_z_index='' link='' link_dynamic='' linktarget='' link_hover='' title_attr='' alt_attr='' mobile_display='' mobile_col_pos='0' id='' custom_class='' template_class='' aria_label='' av_uid='av-2g2390' sc_version='1.0']\n\n[\/av_one_fourth][\/av_section]\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":5355,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5358","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CAD - Digital Engineering - Letolab<\/title>\n<meta name=\"description\" content=\"CAD transforms your ideas into a digital reality. From concept to 3D visualization and production-ready design.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.letolab.nl\/en\/services\/cad-digital-engineering\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAD - Digital Engineering - Letolab\" \/>\n<meta property=\"og:description\" content=\"CAD transforms your ideas into a digital reality. From concept to 3D visualization and production-ready design.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.letolab.nl\/en\/services\/cad-digital-engineering\/\" \/>\n<meta property=\"og:site_name\" content=\"Letolab\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LetoLabDigitalFabrication\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-15T10:01:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/02\/letolab-opengraph.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@leto_lab\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.letolab.nl\/en\/services\/cad-digital-engineering\/\",\"url\":\"https:\/\/www.letolab.nl\/en\/services\/cad-digital-engineering\/\",\"name\":\"CAD - Digital Engineering - Letolab\",\"isPartOf\":{\"@id\":\"https:\/\/www.letolab.nl\/#website\"},\"datePublished\":\"2024-06-11T14:47:56+00:00\",\"dateModified\":\"2025-04-15T10:01:32+00:00\",\"description\":\"CAD transforms your ideas into a digital reality. From concept to 3D visualization and production-ready design.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.letolab.nl\/en\/services\/cad-digital-engineering\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.letolab.nl\/en\/services\/cad-digital-engineering\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.letolab.nl\/en\/services\/cad-digital-engineering\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.letolab.nl\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\/\/www.letolab.nl\/en\/services\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CAD &#8211; Digital Engineering\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.letolab.nl\/#website\",\"url\":\"https:\/\/www.letolab.nl\/\",\"name\":\"Letolab\",\"description\":\"Digital Fabrication ~ Parametric Design\",\"publisher\":{\"@id\":\"https:\/\/www.letolab.nl\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.letolab.nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.letolab.nl\/#organization\",\"name\":\"Letolab\",\"url\":\"https:\/\/www.letolab.nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.letolab.nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/06\/LetoLab-logo.svg\",\"contentUrl\":\"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/06\/LetoLab-logo.svg\",\"width\":300,\"height\":300,\"caption\":\"Letolab\"},\"image\":{\"@id\":\"https:\/\/www.letolab.nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/LetoLabDigitalFabrication\/\",\"https:\/\/x.com\/leto_lab\",\"https:\/\/www.instagram.com\/letolab_digital_fabrication\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAD - Digital Engineering - Letolab","description":"CAD transforms your ideas into a digital reality. From concept to 3D visualization and production-ready design.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.letolab.nl\/en\/services\/cad-digital-engineering\/","og_locale":"en_US","og_type":"article","og_title":"CAD - Digital Engineering - Letolab","og_description":"CAD transforms your ideas into a digital reality. From concept to 3D visualization and production-ready design.","og_url":"https:\/\/www.letolab.nl\/en\/services\/cad-digital-engineering\/","og_site_name":"Letolab","article_publisher":"https:\/\/www.facebook.com\/LetoLabDigitalFabrication\/","article_modified_time":"2025-04-15T10:01:32+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.letolab.nl\/wp-content\/uploads\/2025\/02\/letolab-opengraph.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@leto_lab","twitter_misc":{"Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.letolab.nl\/en\/services\/cad-digital-engineering\/","url":"https:\/\/www.letolab.nl\/en\/services\/cad-digital-engineering\/","name":"CAD - Digital Engineering - Letolab","isPartOf":{"@id":"https:\/\/www.letolab.nl\/#website"},"datePublished":"2024-06-11T14:47:56+00:00","dateModified":"2025-04-15T10:01:32+00:00","description":"CAD transforms your ideas into a digital reality. From concept to 3D visualization and production-ready design.","breadcrumb":{"@id":"https:\/\/www.letolab.nl\/en\/services\/cad-digital-engineering\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.letolab.nl\/en\/services\/cad-digital-engineering\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.letolab.nl\/en\/services\/cad-digital-engineering\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.letolab.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/www.letolab.nl\/en\/services\/"},{"@type":"ListItem","position":3,"name":"CAD &#8211; Digital Engineering"}]},{"@type":"WebSite","@id":"https:\/\/www.letolab.nl\/#website","url":"https:\/\/www.letolab.nl\/","name":"Letolab","description":"Digital Fabrication ~ Parametric Design","publisher":{"@id":"https:\/\/www.letolab.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.letolab.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.letolab.nl\/#organization","name":"Letolab","url":"https:\/\/www.letolab.nl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.letolab.nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/06\/LetoLab-logo.svg","contentUrl":"https:\/\/www.letolab.nl\/wp-content\/uploads\/2024\/06\/LetoLab-logo.svg","width":300,"height":300,"caption":"Letolab"},"image":{"@id":"https:\/\/www.letolab.nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LetoLabDigitalFabrication\/","https:\/\/x.com\/leto_lab","https:\/\/www.instagram.com\/letolab_digital_fabrication\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.letolab.nl\/en\/wp-json\/wp\/v2\/pages\/5358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.letolab.nl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.letolab.nl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.letolab.nl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.letolab.nl\/en\/wp-json\/wp\/v2\/comments?post=5358"}],"version-history":[{"count":23,"href":"https:\/\/www.letolab.nl\/en\/wp-json\/wp\/v2\/pages\/5358\/revisions"}],"predecessor-version":[{"id":6824,"href":"https:\/\/www.letolab.nl\/en\/wp-json\/wp\/v2\/pages\/5358\/revisions\/6824"}],"up":[{"embeddable":true,"href":"https:\/\/www.letolab.nl\/en\/wp-json\/wp\/v2\/pages\/5355"}],"wp:attachment":[{"href":"https:\/\/www.letolab.nl\/en\/wp-json\/wp\/v2\/media?parent=5358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}